{"id":33463,"date":"2022-11-07T10:10:25","date_gmt":"2022-11-07T09:10:25","guid":{"rendered":"https:\/\/nightwatchepilepsy.com\/?page_id=33463"},"modified":"2025-11-26T16:38:15","modified_gmt":"2025-11-26T15:38:15","slug":"politica-di-reso","status":"publish","type":"page","link":"https:\/\/nightwatchepilepsy.com\/it\/politica-di-reso\/","title":{"rendered":"Politica di reso"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<div id=\"comp-kdk2ziwb1\" class=\"_1Q9if\" data-testid=\"richTextElement\">\n<h1 class=\"font_2\"><span>Politica di reso NightWatch+, LivAssured B.V.<\/span><\/h1>\n<\/div>\n<div id=\"comp-kdk2ziwk\" class=\"_1Q9if\" data-testid=\"richTextElement\">\n<p class=\"font_8\"><span>NightWatch+ pu\u00f2 essere reso e il rimborso sar\u00e0 effettuato in base alle seguenti condizioni:<\/span><\/p>\n<\/div>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<table border=\"0\" style=\"border-collapse: collapse; width: 100%; height: 96px; border: 0;\">\n<tbody>\n<tr style=\"height: 24px; background-color: #3d487e; color: #fff;\">\n<td style=\"width: 20%; height: 24px;\">Periodo di reso<\/td>\n<td style=\"height: 24px;\">% di rimborso<\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"height: 24px;\"><span>Entro 30 giorni<\/span><\/td>\n<td style=\"height: 24px;\">100%<\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"height: 24px;\"><span>Da uno a tre mesi <\/span><\/td>\n<td>70%<\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"height: 24px;\"><span>Da quattro a sei mesi\t<\/span><\/td>\n<td style=\"height: 24px;\">50%<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<p>Se decidi di pagare NightWatch+ dopo il periodo di prova di 30 giorni, il pagamento deve essere effettuato per intero allo scadere dei 30 giorni.<\/p>\n<p>Se decidi di restituire NightWatch+, devi registrarti per telefono o e-mail. Riceverai quindi istruzioni dettagliate via e-mail sulla procedura di reso.<\/p>\n<p>Condizioni generali per il reso:<\/p>\n<ul>\n<li>NightWatch+ deve essere reso in perfette condizioni di funzionamento, completo di tutti gli accessori inclusi, custodia da viaggio, manuale e schede plastificate. Non rimuovere le etichette del sensore o della stazione di allarme durante il periodo di prova.<\/li>\n<li>Accertarsi che il sensore NightWatch+ sia spento prima di riporlo nella custodia. Lasciare il sensore in modalit\u00e0 \u201cacceso\u201d per lunghi periodi di tempo senza ricaricarlo pu\u00f2 danneggiare la batteria, specialmente durante il trasporto. In tal caso, potrebbero essere addebitati dei costi.<\/li>\n<li>Se una o pi\u00f9 parti del sistema NightWatch+ risultano mancanti o danneggiate, potrebbero essere addebitati i costi relativi a tali parti. Ci\u00f2 non si applica alla fascia elastica, che sar\u00e0 stata tagliata su misura.<\/li>\n<li>L\u2019acquirente \u00e8 responsabile del reso di NightWatch+ all\u2019indirizzo di ritorno fornito da LivAssured. Si consiglia vivamente di utilizzare un servizio di spedizione affidabile o l\u2019opzione \u201ccon firma\u201d presso l\u2019ufficio postale, poich\u00e9 l\u2019acquirente sar\u00e0 responsabile di eventuali smarrimenti o danni.<\/li>\n<li>Accertarsi che NightWatch+ sia imballato nella confezione originale o in una scatola robusta con materiale di riempimento sufficiente affinch\u00e9 il dispositivo non si sposti e non subisca danni durante il trasporto.<\/li>\n<\/ul>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; hover_enabled=&#8221;0&#8243; sticky_enabled=&#8221;0&#8243;]<\/p>\n<p>Pubblicato il: 29 ottobre 2025, documento CD_LEG18 v1.0<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Politica di reso NightWatch+, LivAssured B.V. NightWatch+ pu\u00f2 essere reso e il rimborso sar\u00e0 effettuato in base alle seguenti condizioni: Periodo di reso % di rimborso Entro 30 giorni 100% Da uno a tre mesi 70% Da quattro a sei mesi 50% Se decidi di pagare NightWatch+ dopo il periodo di prova di 30 giorni, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-33463","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Politica di reso | NightWatch<\/title>\n<meta name=\"description\" content=\"Condizioni di reso\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nightwatchepilepsy.com\/it\/politica-di-reso\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Politica di reso | NightWatch\" \/>\n<meta property=\"og:description\" content=\"Condizioni di reso\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nightwatchepilepsy.com\/it\/politica-di-reso\/\" \/>\n<meta property=\"og:site_name\" content=\"NightWatch\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/EpilepsySeizureDetectionEN\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-26T15:38:15+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Politica di reso | NightWatch\" \/>\n<meta name=\"twitter:description\" content=\"Condizioni di reso\" \/>\n<meta name=\"twitter:site\" content=\"@NightWatchAlarm\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nightwatchepilepsy.com\\\/it\\\/politica-di-reso\\\/\",\"url\":\"https:\\\/\\\/nightwatchepilepsy.com\\\/it\\\/politica-di-reso\\\/\",\"name\":\"Politica di reso | NightWatch\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nightwatchepilepsy.com\\\/it\\\/#website\"},\"datePublished\":\"2022-11-07T09:10:25+00:00\",\"dateModified\":\"2025-11-26T15:38:15+00:00\",\"description\":\"Condizioni di reso\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nightwatchepilepsy.com\\\/it\\\/politica-di-reso\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nightwatchepilepsy.com\\\/it\\\/politica-di-reso\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nightwatchepilepsy.com\\\/it\\\/politica-di-reso\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/nightwatchepilepsy.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Politica di reso\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nightwatchepilepsy.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/nightwatchepilepsy.com\\\/it\\\/\",\"name\":\"NightWatch\",\"description\":\"Epilepsy seizure detection | Warns during sleep\",\"publisher\":{\"@id\":\"https:\\\/\\\/nightwatchepilepsy.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nightwatchepilepsy.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/nightwatchepilepsy.com\\\/it\\\/#organization\",\"name\":\"NightWatch Epilepsy Seizure Detection\",\"alternateName\":\"NightWatch\",\"url\":\"https:\\\/\\\/nightwatchepilepsy.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/nightwatchepilepsy.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/nightwatchepilepsy.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/NightWatch-Logo.png\",\"contentUrl\":\"https:\\\/\\\/nightwatchepilepsy.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/NightWatch-Logo.png\",\"width\":696,\"height\":696,\"caption\":\"NightWatch Epilepsy Seizure Detection\"},\"image\":{\"@id\":\"https:\\\/\\\/nightwatchepilepsy.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/EpilepsySeizureDetectionEN\",\"https:\\\/\\\/x.com\\\/NightWatchAlarm\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/nightwatch-epilepsy-detection\\\/\",\"https:\\\/\\\/www.instagram.com\\\/nightwatch_epilepsie_detectie\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Politica di reso | NightWatch","description":"Condizioni di reso","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nightwatchepilepsy.com\/it\/politica-di-reso\/","og_locale":"it_IT","og_type":"article","og_title":"Politica di reso | NightWatch","og_description":"Condizioni di reso","og_url":"https:\/\/nightwatchepilepsy.com\/it\/politica-di-reso\/","og_site_name":"NightWatch","article_publisher":"https:\/\/www.facebook.com\/EpilepsySeizureDetectionEN","article_modified_time":"2025-11-26T15:38:15+00:00","twitter_card":"summary_large_image","twitter_title":"Politica di reso | NightWatch","twitter_description":"Condizioni di reso","twitter_site":"@NightWatchAlarm","twitter_misc":{"Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nightwatchepilepsy.com\/it\/politica-di-reso\/","url":"https:\/\/nightwatchepilepsy.com\/it\/politica-di-reso\/","name":"Politica di reso | NightWatch","isPartOf":{"@id":"https:\/\/nightwatchepilepsy.com\/it\/#website"},"datePublished":"2022-11-07T09:10:25+00:00","dateModified":"2025-11-26T15:38:15+00:00","description":"Condizioni di reso","breadcrumb":{"@id":"https:\/\/nightwatchepilepsy.com\/it\/politica-di-reso\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nightwatchepilepsy.com\/it\/politica-di-reso\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/nightwatchepilepsy.com\/it\/politica-di-reso\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nightwatchepilepsy.com\/it\/"},{"@type":"ListItem","position":2,"name":"Politica di reso"}]},{"@type":"WebSite","@id":"https:\/\/nightwatchepilepsy.com\/it\/#website","url":"https:\/\/nightwatchepilepsy.com\/it\/","name":"NightWatch","description":"Epilepsy seizure detection | Warns during sleep","publisher":{"@id":"https:\/\/nightwatchepilepsy.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nightwatchepilepsy.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/nightwatchepilepsy.com\/it\/#organization","name":"NightWatch Epilepsy Seizure Detection","alternateName":"NightWatch","url":"https:\/\/nightwatchepilepsy.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/nightwatchepilepsy.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/nightwatchepilepsy.com\/wp-content\/uploads\/2023\/02\/NightWatch-Logo.png","contentUrl":"https:\/\/nightwatchepilepsy.com\/wp-content\/uploads\/2023\/02\/NightWatch-Logo.png","width":696,"height":696,"caption":"NightWatch Epilepsy Seizure Detection"},"image":{"@id":"https:\/\/nightwatchepilepsy.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/EpilepsySeizureDetectionEN","https:\/\/x.com\/NightWatchAlarm","https:\/\/www.linkedin.com\/company\/nightwatch-epilepsy-detection\/","https:\/\/www.instagram.com\/nightwatch_epilepsie_detectie\/"]}]}},"_links":{"self":[{"href":"https:\/\/nightwatchepilepsy.com\/it\/wp-json\/wp\/v2\/pages\/33463","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nightwatchepilepsy.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/nightwatchepilepsy.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/nightwatchepilepsy.com\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/nightwatchepilepsy.com\/it\/wp-json\/wp\/v2\/comments?post=33463"}],"version-history":[{"count":12,"href":"https:\/\/nightwatchepilepsy.com\/it\/wp-json\/wp\/v2\/pages\/33463\/revisions"}],"predecessor-version":[{"id":43774,"href":"https:\/\/nightwatchepilepsy.com\/it\/wp-json\/wp\/v2\/pages\/33463\/revisions\/43774"}],"wp:attachment":[{"href":"https:\/\/nightwatchepilepsy.com\/it\/wp-json\/wp\/v2\/media?parent=33463"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}